{"id":10506,"date":"2024-07-24T14:03:16","date_gmt":"2024-07-24T17:03:16","guid":{"rendered":"https:\/\/manchetebahia.com.br\/?p=10506"},"modified":"2024-07-24T14:03:17","modified_gmt":"2024-07-24T17:03:17","slug":"vitoria-x-flamengo-onde-assistir-arbitragem-e-provaveis-escalacoes","status":"publish","type":"post","link":"https:\/\/manchetebahia.com.br\/index.php\/2024\/07\/24\/vitoria-x-flamengo-onde-assistir-arbitragem-e-provaveis-escalacoes\/","title":{"rendered":"Vit\u00f3ria x Flamengo: onde assistir, arbitragem e prov\u00e1veis escala\u00e7\u00f5es"},"content":{"rendered":"\n<p>Na noite desta quarta-feira (24), Vit\u00f3ria e Flamengo entram em campo no Est\u00e1dio Barrad\u00e3o, em Salvador, para um confronto crucial pela 19\u00aa rodada do Campeonato Brasileiro. O jogo, agendado para as 20h (hor\u00e1rio de Bras\u00edlia), ser\u00e1 transmitido ao vivo pelo canal Premiere.<\/p>\n\n\n\n<p>O Vit\u00f3ria chega para o duelo em meio a uma fase conturbada, com tr\u00eas derrotas seguidas que o fizeram retornar \u00e0 zona de rebaixamento. Diante da press\u00e3o intensa da torcida, o diretor de futebol \u00cdtalo Rodr\u00edguez pediu demiss\u00e3o recentemente, buscando &#8220;pacificar as coisas&#8221; no clube.<\/p>\n\n\n\n<p>Enquanto isso, o Flamengo tenta se reerguer ap\u00f3s perder a lideran\u00e7a do campeonato nas \u00faltimas rodadas. A equipe conseguiu uma vit\u00f3ria importante contra o Crici\u00fama no \u00faltimo fim de semana, com gols de Pedro e Gabigol, e agora busca manter o embalo contra o Vit\u00f3ria.<\/p>\n\n\n\n<p>Para o confronto em Salvador, o t\u00e9cnico Tite ter\u00e1 que lidar com desfalques de \u00faltima hora. Bruno Henrique e Erick Pulgar est\u00e3o fora por les\u00e3o e quest\u00f5es m\u00e9dicas, respectivamente, enquanto Vi\u00f1a e L\u00e9o Pereira retornam \u00e0 equipe titular por op\u00e7\u00e3o do treinador.<\/p>\n\n\n\n<p>As escala\u00e7\u00f5es prov\u00e1veis indicam que o Vit\u00f3ria, sob o comando de Thiago Carpini, pode ter mudan\u00e7as significativas, com a poss\u00edvel estreia de Ricardo Ryller e PK no ataque. J\u00e1 o Flamengo deve contar com nomes como De la Cruz e Everton Cebolinha para dar suporte ao ataque, liderado por Pedro.<\/p>\n\n\n\n<p><strong>Escala\u00e7\u00e3o prov\u00e1vel do Vit\u00f3ria:<\/strong>&nbsp;Lucas Arcanjo; Raul C\u00e1ceres, [Caio Vin\u00edcius], Willean Lepo, Wagner Leonardo e Lucas Esteves; L\u00e9o Naldi, Ricardo Ryller [Everaldo] e Willian Oliveira; Matheusinho, PK [Osvaldo] e Alerrandro.<\/p>\n\n\n\n<p><strong>Pendurados:&nbsp;<\/strong>Lucas Arcanjo, Willian Oliveira, Thiago Carpini, Wagner Leonardo e Matheusinho;<br><strong>Quem est\u00e1 fora:&nbsp;<\/strong>Janderson (suspenso); Luan , Camutanga e Bruno Uvini (les\u00e3o).<\/p>\n\n\n\n<p><strong>Escala\u00e7\u00e3o prov\u00e1vel do Flamengo:<\/strong>&nbsp;Rossi, Varela, Fabr\u00edcio Bruno, L\u00e9o Pereira e Vi\u00f1a; Allan, De la Cruz e Arrascaeta; Gerson, Everton Cebolinha e Pedro.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Arbitragem<\/strong><\/h2>\n\n\n\n<p><strong>\u00c1rbitro:&nbsp;<\/strong>Raphael Claus (FIFA\/SP);<\/p>\n\n\n\n<p><strong>Assistente 1:&nbsp;<\/strong>Marcelo Carvalho Van Gasse (SP);<\/p>\n\n\n\n<p><strong>Assistente 2: D<\/strong>aniel Paulo Ziolli (SP);<\/p>\n\n\n\n<p><strong>Quarto \u00e1rbitro:&nbsp;<\/strong>Matheus Delgado Candan\u00e7an (SP);<\/p>\n\n\n\n<p><strong>VAR:&nbsp;<\/strong>Rodrigo Guarizo Ferreira do Amaral (VAR-FIFA\/SP).<\/p>\n\n\n\n<p>Fonte: Varela Net <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Na noite desta quarta-feira (24), Vit\u00f3ria e Flamengo entram em campo no Est\u00e1dio Barrad\u00e3o, em Salvador, para um confronto crucial pela 19\u00aa rodada do Campeonato Brasileiro. O jogo, agendado para as 20h (hor\u00e1rio de Bras\u00edlia), ser\u00e1 transmitido ao vivo pelo canal Premiere. O Vit\u00f3ria chega para o duelo em meio a uma fase conturbada, com [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":10507,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[89],"tags":[],"class_list":["post-10506","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esportes"],"_links":{"self":[{"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/10506","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=10506"}],"version-history":[{"count":0,"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/10506\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/media\/10507"}],"wp:attachment":[{"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=10506"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=10506"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=10506"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}