{"id":10995,"date":"2024-08-13T10:45:45","date_gmt":"2024-08-13T13:45:45","guid":{"rendered":"https:\/\/manchetebahia.com.br\/?p=10995"},"modified":"2024-08-13T10:45:47","modified_gmt":"2024-08-13T13:45:47","slug":"mulher-e-presa-no-aeroporto-de-guarulhos-com-166-pirulitos-de-cocaina","status":"publish","type":"post","link":"https:\/\/manchetebahia.com.br\/index.php\/2024\/08\/13\/mulher-e-presa-no-aeroporto-de-guarulhos-com-166-pirulitos-de-cocaina\/","title":{"rendered":"Mulher \u00e9 presa no Aeroporto de Guarulhos com 166 pirulitos de coca\u00edna"},"content":{"rendered":"\n<p>No \u00faltimo final de semana uma mulher que n\u00e3o teve a identidade revelada foi presa em flagrante pela Pol\u00edcia Federal de S\u00e3o Paulo embarcando com 166 pirulitos recheados com coca\u00edna. Ela levava consigo cerca de 4kg da droga.<\/p>\n\n\n\n<p>A suspeita que \u00e9 da &nbsp;Nam\u00edbia, um pa\u00eds no sudoeste da \u00c1frica, tinha como destino o Catar, com conex\u00e3o em Angola. Segundo o relato feito pela suspeita \u00e0s autoridades, os pacotes com pirulitos seriam entregues no Congo.<\/p>\n\n\n\n<p>De acordo com a PF, outras cinco pessoas foram presas no aeroporto entre os dias 10 e 11 de agosto.<\/p>\n\n\n\n<p>Um casal de brasileiros foram detidos com 11Kg de coca\u00edna em fundos falsos das malas de viagem que levavam para Portugal. Duas mulheres, tamb\u00e9m brasileiras, que iam viajar com destino a Fran\u00e7a, foram detidas com drogas escondidas pelo corpo. Agentes da Receita Federal, por sua vez, prenderam uma passageira sul-africana que seguia viagem para a Eti\u00f3pia. Ela levava 1kg da droga no fundo falso de sua bagagem.<\/p>\n\n\n\n<p>Fonte: Varela Net <\/p>\n","protected":false},"excerpt":{"rendered":"<p>No \u00faltimo final de semana uma mulher que n\u00e3o teve a identidade revelada foi presa em flagrante pela Pol\u00edcia Federal de S\u00e3o Paulo embarcando com 166 pirulitos recheados com coca\u00edna. Ela levava consigo cerca de 4kg da droga. A suspeita que \u00e9 da &nbsp;Nam\u00edbia, um pa\u00eds no sudoeste da \u00c1frica, tinha como destino o Catar, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":10996,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[105],"tags":[],"class_list":["post-10995","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policia"],"_links":{"self":[{"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/10995","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=10995"}],"version-history":[{"count":0,"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/10995\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/media\/10996"}],"wp:attachment":[{"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=10995"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=10995"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=10995"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}