{"id":12276,"date":"2025-03-11T11:32:51","date_gmt":"2025-03-11T14:32:51","guid":{"rendered":"https:\/\/manchetebahia.com.br\/?p=12276"},"modified":"2025-03-11T11:32:52","modified_gmt":"2025-03-11T14:32:52","slug":"cidades-baianas-estao-sob-alerta-de-chuvas-intensas-veja","status":"publish","type":"post","link":"https:\/\/manchetebahia.com.br\/index.php\/2025\/03\/11\/cidades-baianas-estao-sob-alerta-de-chuvas-intensas-veja\/","title":{"rendered":"Cidades baianas est\u00e3o sob alerta de chuvas intensas; veja"},"content":{"rendered":"<p>O Instituto Nacional de Meteorologia (Inmet) emitiu alerta amarelo de chuvas e ventos intensos para cinco cidades do oeste da Bahia. O alerta foi emitido nesta ter\u00e7a-feira (11) e \u00e9 v\u00e1lido at\u00e9 quarta-feira (12).<\/p>\n<div class=\"flex flex-col p-2 px-0 w-full font-normal text-[18px] leading-[30px] text-tw-theme-text-default\">\n<p id=\"paragrafo-hd7r2kq0na\">As cidades sob aviso s\u00e3o Barreiras,\u00a0Formosa do Rio Preto,\u00a0Lu\u00eds Eduardo Magalh\u00e3es,\u00a0Riach\u00e3o das Neves e\u00a0S\u00e3o Desid\u00e9rio.\u00a0A previs\u00e3o \u00e9 de chuvas intensas &#8211; entre 20 e 30 mm\/h ou at\u00e9 50 mm\/dia &#8211; e ventos intensos &#8211; de 40-60 km\/h, sendo a m\u00e9dia comum de 18 km\/h.<\/p>\n<\/div>\n<div class=\"flex flex-col p-2 px-0 w-full font-normal text-[18px] leading-[30px] text-tw-theme-text-default\">\n<p id=\"paragrafo-k4ba5risu3\">H\u00e1 baixo risco de corte de energia el\u00e9trica, queda de galhos de \u00e1rvores, alagamentos e de descargas el\u00e9tricas.\u00a0A orienta\u00e7\u00e3o \u00e9, em caso de rajadas, n\u00e3o se abrigar debaixo de \u00e1rvores, pois h\u00e1 leve risco de queda e descargas el\u00e9tricas e n\u00e3o estacionar ve\u00edculos pr\u00f3ximos a torres de transmiss\u00e3o e placas de propaganda.<\/p>\n<p>Tamb\u00e9m \u00e9 orientado evitar aparelhos eletr\u00f4nicos ligados \u00e0 tomada. Em caso de emerg\u00eancia, a popula\u00e7\u00e3o pode acionar a Defesa Civil (telefone 199) e o Corpo de Bombeiros (telefone 193).<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>O Instituto Nacional de Meteorologia (Inmet) emitiu alerta amarelo de chuvas e ventos intensos para cinco cidades do oeste da Bahia. O alerta foi emitido nesta ter\u00e7a-feira (11) e \u00e9 v\u00e1lido at\u00e9 quarta-feira (12). As cidades sob aviso s\u00e3o Barreiras,\u00a0Formosa do Rio Preto,\u00a0Lu\u00eds Eduardo Magalh\u00e3es,\u00a0Riach\u00e3o das Neves e\u00a0S\u00e3o Desid\u00e9rio.\u00a0A previs\u00e3o \u00e9 de chuvas intensas &#8211; [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":12278,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[90],"tags":[],"class_list":["post-12276","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bahia"],"_links":{"self":[{"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/12276","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=12276"}],"version-history":[{"count":1,"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/12276\/revisions"}],"predecessor-version":[{"id":12277,"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/12276\/revisions\/12277"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/media\/12278"}],"wp:attachment":[{"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=12276"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=12276"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=12276"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}