{"id":13710,"date":"2026-03-23T13:02:56","date_gmt":"2026-03-23T16:02:56","guid":{"rendered":"https:\/\/manchetebahia.com.br\/?p=13710"},"modified":"2026-03-23T13:02:57","modified_gmt":"2026-03-23T16:02:57","slug":"descarte-irregular-de-entulho-causa-transtornos-na-cidade-e-pode-gerar-multa-veja-como-fazer-o-procedimento-correto-em-salvador","status":"publish","type":"post","link":"https:\/\/manchetebahia.com.br\/index.php\/2026\/03\/23\/descarte-irregular-de-entulho-causa-transtornos-na-cidade-e-pode-gerar-multa-veja-como-fazer-o-procedimento-correto-em-salvador\/","title":{"rendered":"Descarte irregular de entulho causa transtornos na cidade e pode gerar multa; veja como fazer o procedimento correto em Salvador"},"content":{"rendered":"<p>Ao reformar uma casa ou se desfazer de um m\u00f3vel antigo, surge a preocupa\u00e7\u00e3o: como fazer o descarte correto do entulho? A inquieta\u00e7\u00e3o \u00e9 mais que necess\u00e1ria, j\u00e1 que abandonar sobras de constru\u00e7\u00e3o, m\u00f3veis velhos e outros res\u00edduos s\u00f3lidos \u00e9 proibido por lei em Salvador, com previs\u00e3o de multas e outras penalidades para quem descumprir as regras. A norma vale tanto para pessoas f\u00edsicas quanto para pessoas jur\u00eddicas.<\/p>\n<p>H\u00e1, portanto, na capital baiana, pontos exclusivos para esse tipo de descarte: s\u00e3o os ecopontos, locais espalhados pela cidade e criados justamente para evitar o ac\u00famulo irregular de lixo nas ruas, situa\u00e7\u00e3o que pode provocar problemas como alagamentos, entupimento de canais de drenagem e prolifera\u00e7\u00e3o de doen\u00e7as.<\/p>\n<p>Os ecopontos est\u00e3o localizados nos bairros do Itaigara, Itapu\u00e3, Alto da Terezinha, Itacaranha, Bonoc\u00f4 e na Ilha de Bom Jesus dos Passos. Qualquer cidad\u00e3o pode procurar os pontos para fazer o descarte regular dos res\u00edduos, mas \u00e9 preciso estar atento ao limite di\u00e1rio permitido. Conforme a legisla\u00e7\u00e3o municipal, cada pessoa pode descartar, por dia, o equivalente a 50 latas de tinta, 200 carrinhos de m\u00e3o ou 10 ton\u00e9is de res\u00edduos.<\/p>\n<p>A coordenadora de educa\u00e7\u00e3o comunit\u00e1ria da Limpurb, Rosemary Mascarenhas, existe diferen\u00e7a entre o descarte de lixo dom\u00e9stico comum e o descarte de res\u00edduos de constru\u00e7\u00e3o ou os tamb\u00e9m chamados inserv\u00edveis. Essa diferen\u00e7a est\u00e1 principalmente no tipo de material, na forma de coleta e no destino final. O lixo dom\u00e9stico, por exemplo, \u00e9 produzido no dia a dia dentro de casa.<\/p>\n<p>Geralmente \u00e9 recolhido pela coleta p\u00fablica regular da prefeitura, como restos de comida, embalagens, papel e papel\u00e3o, pl\u00e1sticos e guardanapos. O destino \u00e9 normalmente os aterros sanit\u00e1rios ou para programas de reciclagem, quando separado corretamente.<\/p>\n<p>\u201cJ\u00e1 o entulho, s\u00e3o materiais gerados em obras, reformas ou demoli\u00e7\u00f5es, como tijolos, concreto, areia, gesso e telhas. Esse tipo de res\u00edduos n\u00e3o pode ser colocado nos passeios e vias p\u00fablicas, e devem ser encaminhados at\u00e9 um Ecoponto mais pr\u00f3ximo da resid\u00eancia. Os destinos podem ser unidades de reciclagem de entulho ou aterros espec\u00edficos\u201d, explica a coordenadora.<\/p>\n<p>A costureira Maria Oliveira, de 52 anos, moradora do bairro do Toror\u00f3, no Centro da capital baiana, fez uma reforma em sua casa no final do ano passado. Os entulhos foram levados para o Ecoponto da Bonoc\u00f4, com ajuda de um vizinho. \u201cColoquei os baldes em uma carroceria do carro do nosso vizinho e levamos. Eu j\u00e1 sabia que caso descartasse na rua poderia levar multa\u201d, afirmou.<\/p>\n<p>Penalidade &#8211; O descarte irregular de entulho e m\u00f3veis velhos pode gerar multa, cujo valor varia conforme a gravidade da infra\u00e7\u00e3o. A penalidade est\u00e1 prevista na Lei n\u00ba 8.512\/2013. Para pessoas f\u00edsicas, as multas variam de R$ 129,10 a R$ 1.936,44; j\u00e1 para pessoas jur\u00eddicas, os valores v\u00e3o de R$ 516,38 a R$ 3.872,83, podendo ser dobrados em caso de reincid\u00eancia ou quando houver maior risco ao meio ambiente e \u00e0 sa\u00fade p\u00fablica.<\/p>\n<p>\u201cAl\u00e9m de se constituir como crime ambiental, o descarte irregular de res\u00edduos s\u00f3lidos traz diversos preju\u00edzos ao meio ambiente e \u00e0 popula\u00e7\u00e3o, visto que estes pontos irregulares se tornam ambientes prop\u00edcios para a prolifera\u00e7\u00e3o de vetores de doen\u00e7a, levam a gera\u00e7\u00e3o de alagamentos em per\u00edodo de chuva, obstruam as passeios e vias p\u00fablicas, comprometem a qualidade do ambiente e paisagem do local, al\u00e9m de gerar o aumento dos custos p\u00fablicos com a remo\u00e7\u00e3o do material descartado de forma incorreta e tamb\u00e9m dos gastos com sa\u00fade p\u00fablica\u201d, finaliza Rosemary.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ao reformar uma casa ou se desfazer de um m\u00f3vel antigo, surge a preocupa\u00e7\u00e3o: como fazer o descarte correto do entulho? A inquieta\u00e7\u00e3o \u00e9 mais que necess\u00e1ria, j\u00e1 que abandonar sobras de constru\u00e7\u00e3o, m\u00f3veis velhos e outros res\u00edduos s\u00f3lidos \u00e9 proibido por lei em Salvador, com previs\u00e3o de multas e outras penalidades para quem descumprir [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":13712,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[86],"tags":[],"class_list":["post-13710","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salvador"],"_links":{"self":[{"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/13710","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=13710"}],"version-history":[{"count":1,"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/13710\/revisions"}],"predecessor-version":[{"id":13711,"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/13710\/revisions\/13711"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/media\/13712"}],"wp:attachment":[{"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=13710"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=13710"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=13710"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}