{"id":2184,"date":"2023-08-03T16:02:07","date_gmt":"2023-08-03T19:02:07","guid":{"rendered":"https:\/\/manchetebahia.com.br\/?p=2184"},"modified":"2023-08-03T16:02:11","modified_gmt":"2023-08-03T19:02:11","slug":"motorista-e-preso-com-110-mil-cigarros-sem-nota-fiscal-no-oeste-baiano","status":"publish","type":"post","link":"https:\/\/manchetebahia.com.br\/index.php\/2023\/08\/03\/motorista-e-preso-com-110-mil-cigarros-sem-nota-fiscal-no-oeste-baiano\/","title":{"rendered":"Motorista \u00e9 preso com 110 mil cigarros sem nota fiscal no Oeste baiano"},"content":{"rendered":"\n<p>Um homem foi preso em flagrante quando transportava 550 ma\u00e7os de cigarro de origem paraguaia, sem notas fiscais, perto de&nbsp;Paratinga, na regi\u00e3o do Velho Chico, Oeste baiano. Segundo a Pol\u00edcia Militar,&nbsp;o motorista passava por um trecho BA-160 quando foi abordado por&nbsp;agentes da Companhia Independente de Policiamento Rodovi\u00e1rio (CIPRv).<\/p>\n\n\n\n<p>Durante a vistoria, os policiais encontraram os ma\u00e7os em 11 caixas de cigarro. Ap\u00f3s o flagrante, o condutor e o material apreendido foram levados para a delegacia de Bom Jesus da Lapa, na mesma regi\u00e3o. O ve\u00edculo tinha placas do estado de S\u00e3o Paulo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um homem foi preso em flagrante quando transportava 550 ma\u00e7os de cigarro de origem paraguaia, sem notas fiscais, perto de&nbsp;Paratinga, na regi\u00e3o do Velho Chico, Oeste baiano. Segundo a Pol\u00edcia Militar,&nbsp;o motorista passava por um trecho BA-160 quando foi abordado por&nbsp;agentes da Companhia Independente de Policiamento Rodovi\u00e1rio (CIPRv). Durante a vistoria, os policiais encontraram os [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2185,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[105],"tags":[],"class_list":["post-2184","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policia"],"_links":{"self":[{"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2184","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=2184"}],"version-history":[{"count":0,"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2184\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/media\/2185"}],"wp:attachment":[{"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=2184"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=2184"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=2184"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}