{"id":2531,"date":"2023-08-09T14:53:20","date_gmt":"2023-08-09T17:53:20","guid":{"rendered":"https:\/\/manchetebahia.com.br\/?p=2531"},"modified":"2023-08-09T14:53:22","modified_gmt":"2023-08-09T17:53:22","slug":"como-funciona-o-pix-parcelado-ja-adotado-por-alguns-bancos","status":"publish","type":"post","link":"https:\/\/manchetebahia.com.br\/index.php\/2023\/08\/09\/como-funciona-o-pix-parcelado-ja-adotado-por-alguns-bancos\/","title":{"rendered":"Como funciona o Pix parcelado, j\u00e1 adotado por alguns bancos?"},"content":{"rendered":"\n<p>Embora ainda n\u00e3o seja um modalidade oficial de pagamento regulada pelo Banco Central, o Pix parcelado j\u00e1 \u00e9 usado por alguns bancos e fintechs. A modalidade se caracteriza pela possibilidade do cliente escolher em quantas vezes pagar e a melhor data para a parcela ser debitada da conta.<\/p>\n\n\n\n<p>Entretanto, a falta de regula\u00e7\u00e3o por parte do\u00a0Banco Central\u00a0faz com que o servi\u00e7o seja oferecido de diferentes formas, variando conforme a institui\u00e7\u00e3o. Em determinados casos, ele se apresenta como uma forma de pagamento e em outros como mais uma linha de cr\u00e9dito.<\/p>\n\n\n\n<p>No caso de banco tradicional, a autoriza\u00e7\u00e3o do parcelamento passa por an\u00e1lise pr\u00e9via e, mais do que isso, envolve o pagamento de uma taxa. No caso das\u00a0fintechs\u00a0(bancos digitais), o servi\u00e7o funciona um pouco diferente. Ele n\u00e3o envolve o pagamento de juros, mas se o cliente atrasar alguma das parcelas, ele fica sujeito a uma multa fixa.  <\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-bancos-tradicionais\"><strong>Bancos tradicionais<\/strong><\/h3>\n\n\n\n<p>No Ita\u00fa, o aplicativo banc\u00e1rio apresenta a op\u00e7\u00e3o \u201cPague parcelo\u201d quando o cliente inicia uma transfer\u00eancia. \u00c9 poss\u00edvel definir a quantidade de parcelar e a melhor data para o pagamento.<\/p>\n\n\n\n<p>ao fazer uma transfer\u00eancia Pix pelo aplicativo, o cliente pode selecionar a op\u00e7\u00e3o \u201cPague Parcelado\u201d. Em seguida, \u00e9 poss\u00edvel definir a quantidade de parcelar e a melhor data para o pagamento.<\/p>\n\n\n\n<p>J\u00e1 o Banco do Brasil oferece o servi\u00e7o BB Parcela Pix, que possibilita o parcelamento por meio da contrata\u00e7\u00e3o de um empr\u00e9stimo pessoal. Essa op\u00e7\u00e3o est\u00e1 dispon\u00edvel para clientes que possuem limite de cr\u00e9dito dispon\u00edvel a partir de R$ 100.<\/p>\n\n\n\n<p>No Bradesco, a op\u00e7\u00e3o de cr\u00e9dito varia de acordo com o valor da transfer\u00eancia, assim como a taxa de juros varia de acordo com o perfil da opera\u00e7\u00e3o. Um detalhe importante \u00e9 que as taxas de juros variam conforme o prazo do empr\u00e9stimo e o hist\u00f3rico de relacionamento do cliente com o banco.<\/p>\n\n\n\n<p>J\u00e1 o Santander oferece o \u201cDivida o Pix\u201d, servi\u00e7o dispon\u00edvel somente pelo app do banco. O valor m\u00ednimo de contrata\u00e7\u00e3o \u00e9 de R$ 100 e o valor m\u00e1ximo varia de acordo com as condi\u00e7\u00f5es pr\u00e9-aprovadas para o cliente.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Embora ainda n\u00e3o seja um modalidade oficial de pagamento regulada pelo Banco Central, o Pix parcelado j\u00e1 \u00e9 usado por alguns bancos e fintechs. A modalidade se caracteriza pela possibilidade do cliente escolher em quantas vezes pagar e a melhor data para a parcela ser debitada da conta. Entretanto, a falta de regula\u00e7\u00e3o por parte [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2532,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[92],"tags":[],"class_list":["post-2531","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia"],"_links":{"self":[{"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2531","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=2531"}],"version-history":[{"count":0,"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2531\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/media\/2532"}],"wp:attachment":[{"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=2531"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=2531"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=2531"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}