{"id":2764,"date":"2023-08-17T10:47:39","date_gmt":"2023-08-17T13:47:39","guid":{"rendered":"https:\/\/manchetebahia.com.br\/?p=2764"},"modified":"2023-08-17T10:47:41","modified_gmt":"2023-08-17T13:47:41","slug":"antes-de-ser-transformada-em-sufotur-bahiatursa-de-diogo-medrado-fez-contratos-seis-vezes-acima-do-orcamento","status":"publish","type":"post","link":"https:\/\/manchetebahia.com.br\/index.php\/2023\/08\/17\/antes-de-ser-transformada-em-sufotur-bahiatursa-de-diogo-medrado-fez-contratos-seis-vezes-acima-do-orcamento\/","title":{"rendered":"Antes de ser transformada em Sufotur, Bahiatursa de Diogo Medrado fez contratos seis vezes acima do or\u00e7amento"},"content":{"rendered":"\n<p>Em 2022, \u00faltimo ano em que funcionou ainda sobre a marca de Bahiatursa, a Superintend\u00eancia de Fomento ao Turismo da Bahia (Sufotur) praticou um or\u00e7amento seis vezes maior do que tinha dispon\u00edvel em caixa.&nbsp;<\/p>\n\n\n\n<p>Para aquele ano, a Lei Or\u00e7ament\u00e1ria (LOA) previu receita de R$ 38 milh\u00f5es, mas a Superintend\u00eancia ignorou a previs\u00e3o e firmou contratos que chegaram \u00e0 casa dos R$ 206 milh\u00f5es, de acordo com dados do portal da transpar\u00eancia.Assim, muitos contratos foram feitos de maneira irregular, uma vez que a legisla\u00e7\u00e3o n\u00e3o permite tais atos sem que haja dota\u00e7\u00e3o or\u00e7ament\u00e1ria equivalente \u00e0 despesa que se pretende executar.&nbsp;<\/p>\n\n\n\n<p>Pela legisla\u00e7\u00e3o, \u201c\u00e9 proibida a utiliza\u00e7\u00e3o, pelos ordenadores de despesa, de quaisquer procedimentos que viabilizem a execu\u00e7\u00e3o de despesas sem a comprovada e suficiente disponibilidade de dota\u00e7\u00e3o or\u00e7ament\u00e1ria\u201d. A maior parte deles se concentrou entre os meses de junho e setembro, com gastos em festas juninas e at\u00e9 em atos de campanha eleitoral.&nbsp;<\/p>\n\n\n\n<p>Este ano, j\u00e1 sob o nome de Sufotur, a superintend\u00eancia mant\u00e9m o mesmo modelo de atua\u00e7\u00e3o, com um volume de contratos mais que o dobro do seu or\u00e7amento real de R$ 100 milh\u00f5es, autorizado pela Assembleia Legislativa da Bahia (AL-BA) na LOA.&nbsp;<\/p>\n\n\n\n<p>Somente as despesas relacionadas ao per\u00edodo de festejos juninos somaram R$ 194 milh\u00f5es. J\u00e1 no Carnaval, a Sufotur injetou outros R$ 90 milh\u00f5es em cotas de patroc\u00ednios e contrata\u00e7\u00e3o de artistas.&nbsp;<\/p>\n\n\n\n<p>A prop\u00f3sito, o governo assinou contratos com fornecedores e artistas que se apresentaram no Carnaval deste ano em nome da Bahiatursa, mesmo depois do \u00f3rg\u00e3o ter sido extinto. Os contratos, todavia, ficaram com a validade questionada, j\u00e1 que a Bahiatursa n\u00e3o tinha mais representa\u00e7\u00e3o legal e, por conseguinte, n\u00e3o dispunha de or\u00e7amento. Ao mesmo tempo, o governo ainda n\u00e3o havia estabelecido a Sufotur como nova unidade gestora. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Em 2022, \u00faltimo ano em que funcionou ainda sobre a marca de Bahiatursa, a Superintend\u00eancia de Fomento ao Turismo da Bahia (Sufotur) praticou um or\u00e7amento seis vezes maior do que tinha dispon\u00edvel em caixa.&nbsp; Para aquele ano, a Lei Or\u00e7ament\u00e1ria (LOA) previu receita de R$ 38 milh\u00f5es, mas a Superintend\u00eancia ignorou a previs\u00e3o e firmou [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2765,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[98,91],"tags":[],"class_list":["post-2764","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-carnaval","category-politica"],"_links":{"self":[{"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2764","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=2764"}],"version-history":[{"count":0,"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2764\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/media\/2765"}],"wp:attachment":[{"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=2764"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=2764"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=2764"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}