{"id":2985,"date":"2023-08-22T16:06:30","date_gmt":"2023-08-22T19:06:30","guid":{"rendered":"https:\/\/manchetebahia.com.br\/?p=2985"},"modified":"2023-08-22T16:06:40","modified_gmt":"2023-08-22T19:06:40","slug":"iury-castilho-brinca-sobre-contas-para-acesso-do-vitoria-jogador-e-tudo-burro-nao-sabemos-nada-de-matematica","status":"publish","type":"post","link":"https:\/\/manchetebahia.com.br\/index.php\/2023\/08\/22\/iury-castilho-brinca-sobre-contas-para-acesso-do-vitoria-jogador-e-tudo-burro-nao-sabemos-nada-de-matematica\/","title":{"rendered":"Iury Castilho brinca sobre contas para acesso do Vit\u00f3ria: &#8220;Jogador \u00e9 tudo burro, n\u00e3o sabemos nada de matem\u00e1tica&#8221;"},"content":{"rendered":"\n<p>O atacante Iury Castilho revelou, nesta ter\u00e7a-feira (22), que n\u00e3o faz contas para projetar o acesso do Vit\u00f3ria. Ap\u00f3s o t\u00e9rmino da 24\u00aa rodada, o Le\u00e3o foi a 47 pontos e\u00a087,8% de chances de subir para a Primeira Divis\u00e3o.\u00a0<\/p>\n\n\n\n<p>&#8220;Isso a\u00ed \u00e9 para matem\u00e1tico. Jogador \u00e9 tudo burro. N\u00e3o sabemos nada de matem\u00e1tica. O torcedor tem que ficar feliz. A gente tem que jogar bola&#8221;, brincou, em entrevista coletiva.\u00a0<\/p>\n\n\n\n<p>Contratado na \u00faltima janela de transfer\u00eancias, o atleta tem cinco partidas com a camisa do Rubro-Negro baiano e dois gols marcados. O bom come\u00e7o j\u00e1 era esperado por ele.\u00a0<\/p>\n\n\n\n<p>&#8220;Esperava sim. Deu tudo certo. O come\u00e7o tem sido muito bom. Espero continuar dando alegria para a torcida do Vit\u00f3ria&#8221;, pontuou.\u00a0<\/p>\n\n\n\n<p>O Le\u00e3o volta a campo no pr\u00f3ximo domingo (27), \u00e0s 18h, no Ant\u00f4nio Accioly, para enfrentar o Atl\u00e9tico-GO pela 25\u00aa rodada da Segundona. O Drag\u00e3o vem de tr\u00eas vit\u00f3rias consecutivas na competi\u00e7\u00e3o e atualmente \u00e9 o 8\u00ba colocado, com 37 pontos.\u00a0<\/p>\n\n\n\n<p>&#8220;Vamos para uma guerra, vai ser um jogo dif\u00edcil. Vamos buscar os tr\u00eas pontos. Eles v\u00eam em uma crescente muito boa. Tamb\u00e9m estamos na nossa crescente&#8221;, avaliou.\u00a0<\/p>\n\n\n\n<p>Contratado como centroavante, o atleta tem atuado tamb\u00e9m na ponta esquerda do ataque. Ele n\u00e3o determinou prefer\u00eancia de posi\u00e7\u00e3o.\u00a0<\/p>\n\n\n\n<p>&#8220;Minha prefer\u00eancia \u00e9 jogar. Em 2021 eu joguei pouco, e hoje dou muito valor. A alegria muda&#8221;, disse.\u00a0<\/p>\n\n\n\n<p>Por fim, explicou a comemora\u00e7\u00e3o do gol diante do Botafogo-SP na \u00faltima sexta-feira (18). Iury colocou a bola por dentro da blusa e depois a chutou para longe.\u00a0<\/p>\n\n\n\n<p>&#8220;Vou ser pai de novo. Vi um meme do Caz\u00e9 falando que chutei a crian\u00e7a (risos). No pr\u00f3ximo vou dar um beijinho. Vou ser pai de uma menina, se Deus quiser em dezembro ela nasce e me d\u00e1 essa felicidade&#8221;, contou.\u00a0<\/p>\n\n\n\n<p>Fonte: Bahia Not\u00edcias<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O atacante Iury Castilho revelou, nesta ter\u00e7a-feira (22), que n\u00e3o faz contas para projetar o acesso do Vit\u00f3ria. Ap\u00f3s o t\u00e9rmino da 24\u00aa rodada, o Le\u00e3o foi a 47 pontos e\u00a087,8% de chances de subir para a Primeira Divis\u00e3o.\u00a0 &#8220;Isso a\u00ed \u00e9 para matem\u00e1tico. Jogador \u00e9 tudo burro. N\u00e3o sabemos nada de matem\u00e1tica. O torcedor [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2986,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[89,85],"tags":[],"class_list":["post-2985","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esportes","category-noticias"],"_links":{"self":[{"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2985","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=2985"}],"version-history":[{"count":0,"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2985\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/media\/2986"}],"wp:attachment":[{"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=2985"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=2985"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=2985"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}