{"id":6985,"date":"2024-01-17T10:34:03","date_gmt":"2024-01-17T13:34:03","guid":{"rendered":"https:\/\/manchetebahia.com.br\/?p=6985"},"modified":"2024-01-17T10:34:05","modified_gmt":"2024-01-17T13:34:05","slug":"jogo-do-vitoria-pela-2a-rodada-do-campeonato-baiano-e-confirmado-no-barradao","status":"publish","type":"post","link":"https:\/\/manchetebahia.com.br\/index.php\/2024\/01\/17\/jogo-do-vitoria-pela-2a-rodada-do-campeonato-baiano-e-confirmado-no-barradao\/","title":{"rendered":"Jogo do Vit\u00f3ria pela 2\u00aa rodada do Campeonato Baiano \u00e9 confirmado no Barrad\u00e3o"},"content":{"rendered":"\n<p>Neste s\u00e1bado (20) o Vit\u00f3ria estreia no Barrad\u00e3o na temporada 2024, em partida v\u00e1lida pela segunda rodada do Campeonato Baiano contra o Bahia Feira.&nbsp;<\/p>\n\n\n\n<p>Havia uma indefini\u00e7\u00e3o onde o Vit\u00f3ria iria mandar o jogo, por conta de reformas no gramado do Barrad\u00e3o mas as obras terminaram a tempo para o Rubro-Negro estrear no seu santu\u00e1rio em 2024.<\/p>\n\n\n\n<p>A Federa\u00e7\u00e3o Bahiana de Futebol atrav\u00e9s de uma nota, confirmou que a partida ser\u00e1 realizada no Barrad\u00e3o.<\/p>\n\n\n\n<p><em>&#8220;A Federa\u00e7\u00e3o Bahiana de Futebol divulgou nesta segunda-feira (15) uma nova tabela do Baian\u00e3o 2024. Desta vez, foi confirmado o mando de campo do Vit\u00f3ria. O Rubro-Negro mandar\u00e1 seus jogos no Manoel Barradas, o &#8220;Barrad\u00e3o&#8221;. O duelo contra o Bahia de Feira, no pr\u00f3ximo s\u00e1bado (20), pela 2\u00aa rodada, j\u00e1 acontecer\u00e1 no est\u00e1dio.&#8221;&nbsp;<\/em>informou a entidade.<\/p>\n\n\n\n<p><strong>Mudan\u00e7as no Barrad\u00e3o e no entorno<\/strong><\/p>\n\n\n\n<p>N\u00e3o foi s\u00f3 o gramado do Barrad\u00e3o que passou por reformas, o placar eletr\u00f4nico do est\u00e1dio foi trocado ainda em dezembo e no entorno do &#8220;Santu\u00e1rio&#8221; est\u00e1 sendo realizada a obra de duplica\u00e7\u00e3o da via que d\u00e1 acesso ao est\u00e1dio, e tamb\u00e9m a constru\u00e7\u00e3o de um novo estacionamento.&nbsp;<\/p>\n\n\n\n<p>A \u00faltima partida do Vit\u00f3ria no Barrad\u00e3o foi em 2023, quando venceu o Sport ainda pela S\u00e9rie B e na ocasi\u00e3o o Rubro-Negro levantou a ta\u00e7a de Campe\u00e3o e festejou com sua torcida.\u00a0<\/p>\n\n\n\n<p>Fonte: Varela Net <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Neste s\u00e1bado (20) o Vit\u00f3ria estreia no Barrad\u00e3o na temporada 2024, em partida v\u00e1lida pela segunda rodada do Campeonato Baiano contra o Bahia Feira.&nbsp; Havia uma indefini\u00e7\u00e3o onde o Vit\u00f3ria iria mandar o jogo, por conta de reformas no gramado do Barrad\u00e3o mas as obras terminaram a tempo para o Rubro-Negro estrear no seu santu\u00e1rio [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":6986,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[89],"tags":[],"class_list":["post-6985","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esportes"],"_links":{"self":[{"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6985","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=6985"}],"version-history":[{"count":0,"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6985\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/media\/6986"}],"wp:attachment":[{"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=6985"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=6985"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=6985"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}