{"id":8772,"date":"2024-04-30T10:13:09","date_gmt":"2024-04-30T13:13:09","guid":{"rendered":"https:\/\/manchetebahia.com.br\/?p=8772"},"modified":"2024-04-30T10:13:11","modified_gmt":"2024-04-30T13:13:11","slug":"davi-e-sua-irma-tem-perfil-do-instagram-hackeado","status":"publish","type":"post","link":"https:\/\/manchetebahia.com.br\/index.php\/2024\/04\/30\/davi-e-sua-irma-tem-perfil-do-instagram-hackeado\/","title":{"rendered":"Davi e sua irm\u00e3 tem perfil do Instagram hackeado"},"content":{"rendered":"\n<p>O perfil de Davi e de sua irm\u00e3 foram hackeados nesta segunda (29). A confirma\u00e7\u00e3o pelo perfil oficial do ex-brother na plataforma X (antigo Twitter), &#8220;Rackearam a Conta do Instagram de Davi Brito e de Raquel Brito [irm\u00e3 do ex-BBB]!!! Estamos na busca pra recuperamos o acesso!! Pedimos que, por favor, n\u00e3o caiam em nada de mensagens e nem Stories no perfis de Davi Brito e de Raquel Brito!!&#8221;, postou a equipe que ger\u00eancia as suas redes sociais.&nbsp;<\/p>\n\n\n\n<p>A invas\u00e3o no perfil de Davi ocorreu ap\u00f3s foto publicada no feed com a legenda &#8220;Lute com determina\u00e7\u00e3o, abrace a vida com paix\u00e3o, perca com classe e ven\u00e7a com ousadia, porque o mundo pertence a quem se atreve e a vida \u00e9 muito para ser insignificante&#8221;. Logo depois, foram realizadas publica\u00e7\u00f5es em seu stories falando sobre investimentos. A sua equipe rapidamente se pronunciou no X. &nbsp;<\/p>\n\n\n\n<p>Fonte: Varela Net <\/p>\n","protected":false},"excerpt":{"rendered":"<p>O perfil de Davi e de sua irm\u00e3 foram hackeados nesta segunda (29). A confirma\u00e7\u00e3o pelo perfil oficial do ex-brother na plataforma X (antigo Twitter), &#8220;Rackearam a Conta do Instagram de Davi Brito e de Raquel Brito [irm\u00e3 do ex-BBB]!!! Estamos na busca pra recuperamos o acesso!! Pedimos que, por favor, n\u00e3o caiam em nada [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":8773,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[93],"tags":[],"class_list":["post-8772","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimento"],"_links":{"self":[{"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/8772","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=8772"}],"version-history":[{"count":0,"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/8772\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/media\/8773"}],"wp:attachment":[{"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=8772"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=8772"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=8772"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}