{"id":9386,"date":"2024-06-04T15:57:03","date_gmt":"2024-06-04T18:57:03","guid":{"rendered":"https:\/\/manchetebahia.com.br\/?p=9386"},"modified":"2024-06-04T15:57:06","modified_gmt":"2024-06-04T18:57:06","slug":"nao-me-contentaria-com-mais-um-ano-assim-diz-mbappe-sobre-o-psg","status":"publish","type":"post","link":"https:\/\/manchetebahia.com.br\/index.php\/2024\/06\/04\/nao-me-contentaria-com-mais-um-ano-assim-diz-mbappe-sobre-o-psg\/","title":{"rendered":"&#8220;N\u00e3o me contentaria com mais um ano assim&#8221;, diz Mbapp\u00e9 sobre o PSG"},"content":{"rendered":"\n<p>Uma das principais estrelas do futebol mundial, Kylian Mbapp\u00e9 concedeu sua primeira entrevista como\u00a0jogador do Real Madrid, nesta ter\u00e7a-feira, 4. Mesmo oficialmente anunciado como um &#8216;Merengue&#8217; o fr\u00e2nces n\u00e3o respondeu a perguntas sobre a transfer\u00eancia, o motivo? &#8216;N\u00e3o ofuscar a sele\u00e7\u00e3o francesa&#8217;. Entretanto, o jogador falou sobre sua situa\u00e7\u00e3o no PSG:\u00a0 <\/p>\n\n\n\n<p>&#8220;No PSG n\u00e3o fui infeliz, dizer isso seria cuspir no prato que comi. H\u00e1 coisas que me deixaram tristes, mas h\u00e1 coisas que n\u00e3o podem ser mostradas porque eu era um l\u00edder e n\u00e3o se segue algu\u00e9m que est\u00e1 deprimido. Seria meio canalha chegar e dizer que fui infeliz no PSG, mas houve coisas que me deixaram triste e n\u00e3o me contentaria com mais um ano assim&#8221;, afirmou o craque.&nbsp;<\/p>\n\n\n\n<p>Mbapp\u00e9 tamb\u00e9m agradeceu as mensagens de apoio que recebeu no an\u00fancio oficial. &#8220;Quanto \u00e0s mensagens que recebi, n\u00e3o pude ver tudo, mas vi Cristiano Ronaldo, Sergio Ramos, Iker Casillas, meus futuros companheiros e ex-companheiros. \u00c9 um prazer. Agrade\u00e7o e espero fazer jus a isso&#8221;, ressaltou.<\/p>\n\n\n\n<p>Fonte:  A Tarde <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uma das principais estrelas do futebol mundial, Kylian Mbapp\u00e9 concedeu sua primeira entrevista como\u00a0jogador do Real Madrid, nesta ter\u00e7a-feira, 4. Mesmo oficialmente anunciado como um &#8216;Merengue&#8217; o fr\u00e2nces n\u00e3o respondeu a perguntas sobre a transfer\u00eancia, o motivo? &#8216;N\u00e3o ofuscar a sele\u00e7\u00e3o francesa&#8217;. Entretanto, o jogador falou sobre sua situa\u00e7\u00e3o no PSG:\u00a0 &#8220;No PSG n\u00e3o fui [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":9387,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[89],"tags":[],"class_list":["post-9386","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esportes"],"_links":{"self":[{"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/9386","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=9386"}],"version-history":[{"count":0,"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/9386\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/media\/9387"}],"wp:attachment":[{"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=9386"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=9386"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=9386"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}