{"id":9824,"date":"2024-06-27T11:34:15","date_gmt":"2024-06-27T14:34:15","guid":{"rendered":"https:\/\/manchetebahia.com.br\/?p=9824"},"modified":"2024-06-27T11:34:17","modified_gmt":"2024-06-27T14:34:17","slug":"homem-e-torturado-e-encontrado-morto-a-tiros-em-fazenda-na-bahia","status":"publish","type":"post","link":"https:\/\/manchetebahia.com.br\/index.php\/2024\/06\/27\/homem-e-torturado-e-encontrado-morto-a-tiros-em-fazenda-na-bahia\/","title":{"rendered":"Homem \u00e9 torturado e encontrado morto a tiros em fazenda na Bahia"},"content":{"rendered":"\n<p>Um mist\u00e9rio tomou conta de uma fazenda chamada Cancela, na cidade de Cara\u00edbas, no sudoeste da Bahia. O cad\u00e1ver de um homem, identificado como Zenilton Damasceno Santos, de 48 anos, foi encontrado dentro de um carro com marcas de tiro e sinais de tortura na quarta-feira, 26.<\/p>\n\n\n\n<p>As autoridades tomaram ci\u00eancia do acontecimento ap\u00f3s receberem den\u00fancias de disparos, feitas por trabalhadores da fazenda. Agentes da Pol\u00edcia Militar (PM-BA) dirigiram-se ao local e acharam o corpo do homem sem vida e coberto por tiros.<\/p>\n\n\n\n<p>A autoria e motiva\u00e7\u00e3o da fatalidade seguem desconhecidas e ser\u00e3o investigadas pela delegacia de Cara\u00edbas.<\/p>\n\n\n\n<p>A pol\u00edcia informou que o cad\u00e1ver do homem foi retirado pelo Departamento de Pol\u00edcia T\u00e9cnica (DPT) e levado para o Instituto M\u00e9dico Legal (IML) de Vit\u00f3ria da Conquista.<\/p>\n\n\n\n<p>Fonte: A Tarde <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um mist\u00e9rio tomou conta de uma fazenda chamada Cancela, na cidade de Cara\u00edbas, no sudoeste da Bahia. O cad\u00e1ver de um homem, identificado como Zenilton Damasceno Santos, de 48 anos, foi encontrado dentro de um carro com marcas de tiro e sinais de tortura na quarta-feira, 26. As autoridades tomaram ci\u00eancia do acontecimento ap\u00f3s receberem [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":9825,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[105],"tags":[],"class_list":["post-9824","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policia"],"_links":{"self":[{"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/9824","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=9824"}],"version-history":[{"count":0,"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/9824\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/media\/9825"}],"wp:attachment":[{"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=9824"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=9824"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=9824"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}