{"id":9892,"date":"2024-07-03T11:02:59","date_gmt":"2024-07-03T14:02:59","guid":{"rendered":"https:\/\/manchetebahia.com.br\/?p=9892"},"modified":"2024-07-03T11:03:01","modified_gmt":"2024-07-03T14:03:01","slug":"dorival-jr-critica-arbitragem-em-nao-marcacao-de-penalti-decisivo","status":"publish","type":"post","link":"https:\/\/manchetebahia.com.br\/index.php\/2024\/07\/03\/dorival-jr-critica-arbitragem-em-nao-marcacao-de-penalti-decisivo\/","title":{"rendered":"Dorival Jr critica arbitragem em n\u00e3o marca\u00e7\u00e3o de p\u00eanalti: &#8220;Decisivo&#8221;"},"content":{"rendered":"\n<p>A Sele\u00e7\u00e3o Brasileira empatou com a Col\u00f4mbia nesta ter\u00e7a-feira, 2, pela \u00faltima rodada do grupo D da Copa Am\u00e9rica. Assim, nas quartas de final enfrentar\u00e1 o Uruguai, l\u00edder do grupo C, que terminou a primeira fase com 100% de aproveitamento. Durante coletiva de imprensa ap\u00f3s o jogo, o treinador Dorival Jr avaliou a partida e destacou um lance espec\u00edfico: o poss\u00edvel p\u00eanalti n\u00e3o marcado em Vinicius Jr.<\/p>\n\n\n\n<p>Na ocasi\u00e3o, o Brasil vencia por 1&#215;0, tendo chance de aumentar a vantagem. Assim, Dorival definiu a atitude da arbitragem como decisiva, tendo em vista que sofreu o gol de empate nos minutos seguintes, perdendo a primeira coloca\u00e7\u00e3o do grupo.<\/p>\n\n\n\n<p>\u201cNaquele momento seriam 2 a 0. Um placar de 2 a 0, com a velocidade que n\u00f3s temos, com a equipe que n\u00f3s temos, independentemente de as coisas n\u00e3o estarem saindo como n\u00f3s gostar\u00edamos que estivessem, seria muito diferente de um resultado de 1 a 0. E logo em seguida n\u00f3s acabamos de tomar o gol de empate. Foi (a n\u00e3o marca\u00e7\u00e3o do p\u00eanalti) decisivo&#8221;, disse o treinador.<\/p>\n\n\n\n<p>Em continuidade, Dorival opinou que o jogo seria outro, em caso de 2&#215;0. Segundo ele, a Col\u00f4mbia teria que se expor mais, o que poderia facilitar o jogo da amarelinha.<\/p>\n\n\n\n<p>\u201cAli n\u00e3o tenho d\u00favidas de que as movimenta\u00e7\u00f5es da partida seriam outras. A sele\u00e7\u00e3o colombiana teria que se expor mais. Talvez pud\u00e9ssemos tirar proveito de uma situa\u00e7\u00e3o que sabemos como ningu\u00e9m jogar, que \u00e9 justamente a de ter transi\u00e7\u00f5es facilitadas pela velocidade e t\u00e9cnica de nossa equipe&#8221;, concluiu.<\/p>\n\n\n\n<p>Para o duelo diante do Uruguai, o Brasil n\u00e3o contar\u00e1 com o jogador Vinicius Jr, que recebeu o segundo cart\u00e3o amarelo e desfalca o elenco. Sobre o acontecido, o comandante afirmou que o jogo era muito importante e n\u00e3o poderia poupar ningu\u00e9m.<\/p>\n\n\n\n<p>\u201c\u00c9 uma situa\u00e7\u00e3o que aconteceu, \u00e9 do jogo. Era um jogo muito importante e eu n\u00e3o tinha como segurar ningu\u00e9m num momento como esse. O que n\u00f3s quer\u00edamos era o resultado. Iniciamos muito bem a partida e, por incr\u00edvel que pare\u00e7a, no primeiro lance, que para mim foi casual, acabamos tendo j\u00e1 o cart\u00e3o amarelo do Vinicius\u201d, disse Dorival.<\/p>\n\n\n\n<p>A Sele\u00e7\u00e3o volta a campo neste s\u00e1bado, 6, \u00e0s 22h, no Allegiant Stadium, em Las Vegas, contra o Uruguai, pelas quartas de final da Copa Am\u00e9rica.<\/p>\n\n\n\n<p>Fonte: A Tarde <\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Sele\u00e7\u00e3o Brasileira empatou com a Col\u00f4mbia nesta ter\u00e7a-feira, 2, pela \u00faltima rodada do grupo D da Copa Am\u00e9rica. Assim, nas quartas de final enfrentar\u00e1 o Uruguai, l\u00edder do grupo C, que terminou a primeira fase com 100% de aproveitamento. Durante coletiva de imprensa ap\u00f3s o jogo, o treinador Dorival Jr avaliou a partida e [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":9893,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[89],"tags":[],"class_list":["post-9892","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esportes"],"_links":{"self":[{"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/9892","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=9892"}],"version-history":[{"count":0,"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/9892\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/media\/9893"}],"wp:attachment":[{"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=9892"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=9892"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/manchetebahia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=9892"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}